{"id":8333,"date":"2022-06-29T00:59:42","date_gmt":"2022-06-29T04:59:42","guid":{"rendered":"https:\/\/mitocanada.org\/zach-seymour\/"},"modified":"2026-05-07T18:51:47","modified_gmt":"2026-05-07T22:51:47","slug":"zach-seymour","status":"publish","type":"post","link":"https:\/\/mitocanada.org\/fr\/zach-seymour\/","title":{"rendered":"Zach Seymour"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1456px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\" style=\"border-radius:14px;\"><img decoding=\"async\" width=\"800\" height=\"234\" title=\"Faces of Mito &#8211; Seymour\" src=\"https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/Faces-of-Mito-Seymour.png\" alt class=\"img-responsive wp-image-14283\" srcset=\"https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/Faces-of-Mito-Seymour-200x59.png 200w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/Faces-of-Mito-Seymour-400x117.png 400w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/Faces-of-Mito-Seymour-600x176.png 600w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/Faces-of-Mito-Seymour.png 800w\" sizes=\"(max-width: 640px) 100vw, 800px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\"><div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Zach Seymour est un expert de la vie avec une maladie mitochondriale. Il n&rsquo;en est pas atteint lui-m\u00eame, mais sa m\u00e8re et son fr\u00e8re le sont. <\/p>\n<p>\u00c0 l&rsquo;\u00e2ge de 12 ans, Zach dirigeait la maison. Il faisait le m\u00e9nage, aidait \u00e0 \u00e9lever son jeune fr\u00e8re et s&rsquo;appuyait sur ses grands-parents pour tout \u00e9quilibrer. <\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Pendant ce temps, la m\u00e8re de Zach souffrait de fatigue chronique et dormait 14 heures par jour. M\u00e8re c\u00e9libataire de deux enfants, elle occupait plusieurs emplois pour tenter de joindre les deux bouts &#8211; quand elle le pouvait. <\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Elle soup\u00e7onnait une maladie mitochondriale, mais ne parvenait pas \u00e0 convaincre les m\u00e9decins de leur petite ville rurale qu&rsquo;il s&rsquo;agissait d&rsquo;une possibilit\u00e9. C&rsquo;\u00e9tait d\u00e9moralisant, frustrant et d\u00e9bilitant, car ce manque de volont\u00e9 d&rsquo;envisager la maladie mitochondriale les a laiss\u00e9s sans diagnostic. <\/p>\n<blockquote>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>L&rsquo;absence de diagnostic signifiait \u00e9galement l&rsquo;absence de traitement, de soulagement, de soutien ou d&rsquo;espoir.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Les personnes ext\u00e9rieures n&rsquo;\u00e9taient pas conscientes des d\u00e9fis incroyables auxquels Zach et sa famille \u00e9taient confront\u00e9s. Ce beau jeune homme r\u00e9ussissait tr\u00e8s bien \u00e0 l&rsquo;\u00e9cole, il \u00e9tait capitaine de plusieurs \u00e9quipes sportives et il ne se plaignait pas et ne demandait pas d&rsquo;aide. <\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p><b><img decoding=\"async\" class=\"alignright wp-image-3292\" src=\"https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568.png\" alt=\"Zach, son fr\u00e8re et sa m\u00e8re posent et sourient devant des fleurs\" width=\"281\" height=\"282\" srcset=\"https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568-66x66.png 66w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568-150x150.png 150w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568-200x200.png 200w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568-300x300.png 300w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568-400x401.png 400w, https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/4-e1686279028568.png 432w\" sizes=\"(max-width: 281px) 100vw, 281px\" \/><\/b>Adolescent, Zach avait l&rsquo;impression que lui et sa famille vivaient dans une sorte de vide \u00e9trange. Son fr\u00e8re a \u00e9galement d\u00e9velopp\u00e9 une fatigue chronique. Ils savaient que ce qu&rsquo;ils vivaient n&rsquo;\u00e9tait pas normal, mais aucune infrastructure n&rsquo;\u00e9tait en place pour les mettre sur la sellette. Zach s&rsquo;est efforc\u00e9 de d\u00e9fendre les int\u00e9r\u00eats de sa famille, mais il n&rsquo;a pas r\u00e9ussi \u00e0 obtenir les soins et le soutien dont elle avait besoin.   <\/p>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>\u00c0 l&rsquo;\u00e2ge de 16 ans, Zach a commenc\u00e9 \u00e0 pr\u00e9senter des sympt\u00f4mes similaires \u00e0 ceux de sa m\u00e8re et de son fr\u00e8re cadet. Il \u00e9tait \u00e9puis\u00e9, souvent \u00e9tourdi et naus\u00e9eux. Il souffrait de maux de t\u00eate d\u00e9bilitants et avait du mal \u00e0 se concentrer. Ses capacit\u00e9s athl\u00e9tiques diminuent et ses notes baissent. Ses mains ont commenc\u00e9 \u00e0 trembler. Il a souffert de d\u00e9pression.     <\/p>\n<blockquote>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Zach croyait avoir d\u00e9velopp\u00e9 une mitose. Ce n&rsquo;\u00e9tait pas le cas. Zach avait une tumeur c\u00e9r\u00e9brale de 5,5 cm qui a \u00e9t\u00e9 diagnostiqu\u00e9e trois ans plus tard.  <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"page\" title=\"Page 1\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p>Au cours de l&rsquo;\u00e9t\u00e9 suivant sa premi\u00e8re ann\u00e9e d&rsquo;universit\u00e9, Zach a \u00e9t\u00e9 transport\u00e9 d&rsquo;urgence \u00e0 l&rsquo;h\u00f4pital d&rsquo;un grand centre urbain o\u00f9 il a subi une intervention chirurgicale de 14 heures pour retirer la tumeur c\u00e9r\u00e9brale. Au cours des semaines et des mois qui ont suivi, il a men\u00e9 &#8211; et gagn\u00e9 &#8211; de nombreuses batailles. Il a d\u00fb r\u00e9apprendre \u00e0 marcher et \u00e0 parler. Il devait reprendre les 30 livres et les muscles athl\u00e9tiques qu&rsquo;il avait perdus. Il n&rsquo;\u00e9tait plus le m\u00eame.    <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:25px;width:100%;\"><\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:#ffffff;--awb-title-color:#000000;--awb-content-color:#000000;--awb-icon-box-color:#119bb5;--awb-toggle-hover-accent-color:#119bb5;--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:20px;--awb-title-letter-spacing:-0.015em;--awb-title-line-height:1.2;--awb-content-font-family:&quot;Montserrat&quot;;--awb-content-font-style:normal;--awb-content-font-weight:400;\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-8333-1\"><div class=\"fusion-panel panel-default panel-db9a20277cc08492e fusion-toggle-has-divider\" style=\"--awb-title-color:#000000;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_db9a20277cc08492e\"><a aria-expanded=\"false\" aria-controls=\"db9a20277cc08492e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-8333-1\" data-target=\"#db9a20277cc08492e\" href=\"#db9a20277cc08492e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Garder le moral <\/span><\/a><\/h4><\/div><div id=\"db9a20277cc08492e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_db9a20277cc08492e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>On aurait pu penser que cette exp\u00e9rience lui ferait perdre le moral, mais Zach d\u00e9clare : \u00ab\u00a0J&rsquo;ai eu l&rsquo;impression qu&rsquo;on m&rsquo;offrait une occasion en or. Je n&rsquo;avais plus de singe sur le dos. Je devais repartir de z\u00e9ro, mais j&rsquo;\u00e9tais en bonne sant\u00e9 pour la premi\u00e8re fois de ma vie. Je savais que j&rsquo;\u00e9tais capable de tant de choses et que je ne me contenterais pas de vaincre cette maladie, mais que je vivrais pour aider les autres.\u00a0\u00bb<\/p>\n<blockquote><p>Et aider les autres, c&rsquo;est exactement ce que fait Zach en tant que nouveau membre du conseil d&rsquo;administration de MitoCanada. Il se dit enthousiaste \u00e0 l&rsquo;id\u00e9e de faire partie de la communaut\u00e9 mito et d\u00e9sireux d&rsquo;aider l&rsquo;organisation \u00e0 cro\u00eetre, \u00e0 accro\u00eetre la sensibilisation aux d\u00e9fis auxquels les patients mito sont confront\u00e9s chaque jour et \u00e0 am\u00e9liorer la vie des personnes vivant avec la mito. <\/p><\/blockquote>\n<p>Cela a d\u00e9j\u00e0 commenc\u00e9 avec sa m\u00e8re et son fr\u00e8re, chez qui on a finalement diagnostiqu\u00e9 une maladie mitotique. Zach les soutient tous les deux. Son fr\u00e8re entre \u00e0 l&rsquo;universit\u00e9. Le processus est lent, car il a besoin d&rsquo;am\u00e9nagements sp\u00e9ciaux, tels que du temps suppl\u00e9mentaire pour les examens, des d\u00e9lais flexibles et du temps pour se reposer lorsque ses muscles sont faibles. Zach dit que son fr\u00e8re est intelligent et d\u00e9termin\u00e9, mais il accepte \u00e0 contrec\u0153ur qu&rsquo;il devra trouver un mode de vie non conventionnel, car la routine traditionnelle du 9 \u00e0 5 n&rsquo;est pas une option. Le fr\u00e8re de Zach accepte \u00e9galement que la personne avec laquelle il choisit de partager sa vie partage \u00e9galement certaines de ses limites.     <\/p>\n<p>\u00ab\u00a0Je suis tellement reconnaissant que mon voyage ait eu une date de fin\u00a0\u00bb, affirme Zach. \u00ab\u00a0Je suis capable de fonctionner bien au-del\u00e0 de la normale et je peux maintenant rendre service aux autres. <span class=\"Apple-converted-space\">  <\/span>Alors que sa famille avait l&rsquo;habitude de lutter contre des sentiments d&rsquo;isolement et de d\u00e9sespoir, Zach affirme que \u00ab\u00a0mon exp\u00e9rience nous a tous motiv\u00e9s \u00e0 trouver des solutions. Mon engagement envers MitoCanada nous aidera \u00e0 trouver ces solutions.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-73a1c9d6b5b7f1f71 fusion-toggle-has-divider\" style=\"--awb-title-color:#000000;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_73a1c9d6b5b7f1f71\"><a aria-expanded=\"false\" aria-controls=\"73a1c9d6b5b7f1f71\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-8333-1\" data-target=\"#73a1c9d6b5b7f1f71\" href=\"#73a1c9d6b5b7f1f71\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Soutenir la communaut\u00e9 Mito<\/span><\/a><\/h4><\/div><div id=\"73a1c9d6b5b7f1f71\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_73a1c9d6b5b7f1f71\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>D\u00e9termin\u00e9 \u00e0 contribuer \u00e0 la cr\u00e9ation d&rsquo;un monde o\u00f9 il existe des traitements qui peuvent aider toutes les personnes atteintes de mitose, Zach veut que la communaut\u00e9 mitotique soit en meilleure sant\u00e9 afin qu&rsquo;elle ait la force de terminer l&rsquo;\u00e9ducation dont elle a besoin pour contribuer, travailler pour subvenir \u00e0 ses besoins et profiter de la vie.<\/p>\n<p>La famille de Zach continue de chercher des th\u00e9rapies qui r\u00e9soudront leurs sympt\u00f4mes. Ils prennent tous deux un cocktail mito, font de l&rsquo;exercice lorsqu&rsquo;ils le peuvent et participent \u00e0 plusieurs essais cliniques. <\/p>\n<p>Zach se souvient de ce que c&rsquo;\u00e9tait que de ne pas \u00eatre diagnostiqu\u00e9. \u00ab\u00a0Les cons\u00e9quences de ma maladie resteront grav\u00e9es dans ma m\u00e9moire pour le reste de ma vie\u00a0\u00bb, d\u00e9clare-t-il. \u00ab\u00a0Je suis toujours en col\u00e8re et anxieux lorsque je repense \u00e0 la p\u00e9riode o\u00f9 mes probl\u00e8mes de sant\u00e9 ont \u00e9t\u00e9 ignor\u00e9s et o\u00f9 les professeurs et les entra\u00eeneurs m&rsquo;ont qualifi\u00e9 de paresseux et de gaspilleur de mon talent et de mon potentiel.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-c07610a526890b20e fusion-toggle-has-divider\" style=\"--awb-title-color:#000000;\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_c07610a526890b20e\"><a aria-expanded=\"false\" aria-controls=\"c07610a526890b20e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-8333-1\" data-target=\"#c07610a526890b20e\" href=\"#c07610a526890b20e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Apprendre gr\u00e2ce \u00e0 une exp\u00e9rience personnelle douloureuse<\/span><\/a><\/h4><\/div><div id=\"c07610a526890b20e\" class=\"panel-collapse collapse \" aria-labelledby=\"toggle_c07610a526890b20e\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<blockquote><p>Zach affirme que lorsque vous ne pouvez pas d\u00e9fendre vos int\u00e9r\u00eats, vous \u00eates laiss\u00e9 pour compte.<\/p><\/blockquote>\n<p>Il se demande comment on peut attendre de ceux qui ont moins de capacit\u00e9s, de connaissances et de soutien que sa m\u00e8re, forte et intelligente, qu&rsquo;ils se d\u00e9fendent eux-m\u00eames. Il compatit avec ceux qui savent qu&rsquo;ils sont capables de tant de choses, mais qui sont frein\u00e9s par quelque chose qu&rsquo;ils ne peuvent pas contr\u00f4ler. <\/p>\n<p>En tant qu&rsquo;ancien patient et d\u00e9fenseur des patients, Zach affirme que les gens doivent continuer \u00e0 raconter leur histoire. Il insiste \u00e9galement sur le fait que les professionnels de la sant\u00e9 doivent vraiment \u00e9couter ce que les patients ont \u00e0 dire et faire preuve d&#8217;empathie, plut\u00f4t que de poser un diagnostic avant d&rsquo;avoir une vue d&rsquo;ensemble de la situation. <\/p>\n<p>Aujourd&rsquo;hui, en tant qu&rsquo;avocat plaidant, Zach est fier de d\u00e9fendre les int\u00e9r\u00eats des autres. Il dit vouloir aider les personnes atteintes de mitose \u00e0 retrouver &#8211; ou \u00e0 d\u00e9couvrir pour la premi\u00e8re fois &#8211; la capacit\u00e9 d&rsquo;exercer leur intelligence, de tirer parti de leur cr\u00e9ativit\u00e9 et d&rsquo;avoir le sentiment de pouvoir vivre une vie saine et \u00e9panouie. <\/p>\n<p>Bien que nous soyons sinc\u00e8rement d\u00e9sol\u00e9s que Zach et sa famille aient travers\u00e9 une telle \u00e9preuve, nous sommes enthousiastes et reconnaissants que cet incroyable survivant ait choisi de partager sa passion, sa compassion, son expertise et son \u00e9nergie avec MitoCanada.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:25px;width:100%;\"><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/mitocanada.org\/wp-content\/uploads\/2022\/06\/1-Faces-of-Mito-Profile-Zach-Seymour.pdf\"><span class=\"fusion-button-text\">T\u00c9L\u00c9CHARGER L&rsquo;HISTOIRE DE ZACH<\/span><\/a><\/div><div class=\"fusion-text fusion-text-2\"><h3>\u00a9 MitoCanada 2022. Partag\u00e9 avec la permission de l&rsquo;auteur. Pas de r\u00e9utilisation ou d&rsquo;adaptation sans consentement.  <\/h3>\n<\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":14283,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[52],"tags":[],"class_list":["post-8333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-les-visages-de-mito"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/posts\/8333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/comments?post=8333"}],"version-history":[{"count":7,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/posts\/8333\/revisions"}],"predecessor-version":[{"id":15761,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/posts\/8333\/revisions\/15761"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/media\/14283"}],"wp:attachment":[{"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/media?parent=8333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/categories?post=8333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mitocanada.org\/fr\/wp-json\/wp\/v2\/tags?post=8333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}